{"id":175,"date":"2016-10-22T21:04:11","date_gmt":"2016-10-22T21:04:11","guid":{"rendered":"http:\/\/aaria-tv.com\/wpzeri\/?p=175"},"modified":"2026-07-14T16:41:50","modified_gmt":"2026-07-14T16:41:50","slug":"benedetto-fifty-years-ago","status":"publish","type":"post","link":"http:\/\/aaria-tv.com\/wpzeri\/2016\/10\/22\/benedetto-fifty-years-ago\/","title":{"rendered":"Benedetto, fifty years ago"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">En 1966, la Nouvelle Compagnie d&rsquo;Avignon cr\u00e9e au Th\u00e9\u00e2tre des Carmes pendant le\u00a0festival, Statues, une pi\u00e8ce d&rsquo;Andr\u00e9 Benedetto.<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Le TNP&nbsp;avait donn\u00e9 les Troyennes \u00e0 la cour d&rsquo;honneur, adaptation de Sartre, avec E.Hirt et Judith Magre. Puis B\u00e9jart entra en danse dans le lieu. Grands souvenirs.<br>On \u00e9tait venus de Rodez en mobylette et nous campions \u00e0 la Barthelasse, \u00e0 regarder le Rh\u00f4ne jusqu&rsquo;au matin. Le festival avait seulement la cour d&rsquo;honneur et le parvis du petit Palais comme lieux, le Verger pour discuter, et la place de l&rsquo;horloge pour continuer la palabre toute&nbsp;la nuit.<br>Ren\u00e9 Duran avait rep\u00e9r\u00e9 une toute petite affiche imprim\u00e9e au pochoir et coll\u00e9e \u00e0 intervalles r\u00e9guliers sur le garde corps du pont Daladier. Dans une boulangerie du quartier des Carmes, j&rsquo;avais remarqu\u00e9 la&nbsp;sculpture baroque&nbsp;de Georges Beaumont qui invitait au spectacle \u00ab\u00a0Statues\u00a0\u00bb. &nbsp;Bref, on a \u00e9t\u00e9 voir. Ils faisaient des tarifs \u00e9tudiants et ch\u00f4meurs. Une porte d&rsquo;entr\u00e9e vitr\u00e9e en bois verni \u00e0 cot\u00e9 d&rsquo;un garage Simca. &nbsp;Une petite caissi\u00e8re rieuse&nbsp;sortant tout droit d&rsquo;un film de J.Eustache nous fait les tickets \u00e0 la main. Un couloir, puis un espace cubique qui contient la sc\u00e8ne et les spectateurs. Ce jour l\u00e0, on \u00e9tait six en tout, assis sur des si\u00e8ges rustiques&nbsp;familiers aux cin\u00e9philes. Les \u00e9chelles \u00e9taient en bois, le grill technique, espac\u00e9 nombre d&rsquo;or, \u00e9galement. Le d\u00e9cor \u00e9tait une sculpture d&rsquo;objets us\u00e9s. La main de l&rsquo;ouvrier \u00e9tait subliminalement&nbsp;partout.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le noir. Une voix dans le noir, qui d\u00e9j\u00e0 le tient \u00e0 distance. Miouzic&#8230; et c&rsquo;est la lumi\u00e8re qui vient. A l&rsquo;int\u00e9rieur du cube, deux cubes, avec les\u00a0acteurs plant\u00e9s dessus. Tr\u00e8s proches de nous, \u00e0 port\u00e9e de main , sans protection chor\u00e9graphique. Le texte comme fumerolles \u00e9clair\u00e9es de l&rsquo;int\u00e9rieur au dessus du magma. Je crois entendre\u00a0quelque malice entre les cubes et l&rsquo;H\u00e9cube des Troyennes, et\u00a0dans cet espace clos il y a\u00a0l&rsquo;univers\u00a0entier, tout\u00a0l&rsquo;espace des questions, intravagantes, extravagantes. Mais c&rsquo;est aussi un tableau achev\u00e9 de peintre, une variation de gris et de couleurs d\u00e9lav\u00e9es, un retable pa\u00efen. Une banderole de papier se d\u00e9roule \u00ab\u00a0lib\u00e9rez le vietnam\u00a0\u00bb, c&rsquo;est pour le maintenant, avec en sous titre \u00a0le tempo, c&rsquo;est pour la musique. Le g\u00e9ant Atlas passe charg\u00e9 de son monde en ruine, c&rsquo;est pour le mythe. L&rsquo;actrice a des allures de cantatrice proph\u00e9tesse grecque. Lui, par moments, dans son costume empes\u00e9, pourrait \u00eatre ce Godot enfin arriv\u00e9 de nulle part. Entre les deux, la petite fille installe le rectangle bleu satur\u00e9\u00a0d&rsquo;une piscine voulue.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">On \u00e0 d\u00e9couvert ce jour l\u00e0 le th\u00e9\u00e2tre Totol, parce que ce th\u00e9\u00e2tre contenait l&rsquo;autre. Il avait l&rsquo;inspiration, l&rsquo;\u00e2me et les armes dont nous avions alors besoin. Puis on a discut\u00e9 un peu avec ce gitan lanceur de couteaux et cette Compagnie si accueillante. On en a parl\u00e9 aux potes, on est revenus. Dans l&rsquo;hiver qui suivit, Andr\u00e9 nous envoya&nbsp;\u00e0 Rodez&nbsp;une longue lettre tap\u00e9e en rouge majuscule sur du papier pelure, histoire de dire, on pourrait faire \u00e9quip\u00e9e. C&rsquo;est ce qu&rsquo;on \u00e0 fait, finalement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Maintenant, cinquante ans plus tard, le 7 juillet 2016 au matin, on a pos\u00e9 la plaque du cr\u00e9ateur du OFF. \u00c9trange distorsion. \u00a0C&rsquo;est le th\u00e9\u00e2tre IN\u00a0qui a \u00e9t\u00e9 r\u00e9-invent\u00e9 ici.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">jmp\/06\/2016<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/media.urgentcrier.com\/urgentcrier\/statues_Mnouchkine_2016_web.mp4\">Voir quelques images de la c\u00e9r\u00e9monie<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/media.urgentcrier.com\/archives\/statues_1280_son_dia.mp4\" target=\"_blank\" rel=\"noreferrer noopener\">Voir le montage avec les photos de Statues prises par Marianne Ahrne en 1966 et&nbsp;les voix d&rsquo;Andr\u00e9 et Jacqueline enregistr\u00e9es en 1996 un jour d&rsquo;orage&nbsp;<\/a>)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/media.urgentcrier.com\/urgentcrier\/TEXTURES_BENEDETTO_1920_2023_web.mp4\">Voir le film \u00ab\u00a0TEXTURES\u00a0\u00bb, 1h20, r\u00e9alis\u00e9 par JM Peytavin<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En 1966, la Nouvelle Compagnie d&rsquo;Avignon cr\u00e9ait au Th\u00e9\u00e2tre des Carmes pendant le festival, Statues, une pi\u00e8ce d&rsquo;Andr\u00e9 Benedetto.<\/p>\n","protected":false},"author":1,"featured_media":169,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,11],"tags":[],"class_list":["post-175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-commentaires","category-evene"],"_links":{"self":[{"href":"http:\/\/aaria-tv.com\/wpzeri\/wp-json\/wp\/v2\/posts\/175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/aaria-tv.com\/wpzeri\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/aaria-tv.com\/wpzeri\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/aaria-tv.com\/wpzeri\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/aaria-tv.com\/wpzeri\/wp-json\/wp\/v2\/comments?post=175"}],"version-history":[{"count":11,"href":"http:\/\/aaria-tv.com\/wpzeri\/wp-json\/wp\/v2\/posts\/175\/revisions"}],"predecessor-version":[{"id":3909,"href":"http:\/\/aaria-tv.com\/wpzeri\/wp-json\/wp\/v2\/posts\/175\/revisions\/3909"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/aaria-tv.com\/wpzeri\/wp-json\/wp\/v2\/media\/169"}],"wp:attachment":[{"href":"http:\/\/aaria-tv.com\/wpzeri\/wp-json\/wp\/v2\/media?parent=175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/aaria-tv.com\/wpzeri\/wp-json\/wp\/v2\/categories?post=175"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/aaria-tv.com\/wpzeri\/wp-json\/wp\/v2\/tags?post=175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}